{"id":11862,"date":"2022-04-15T07:35:35","date_gmt":"2022-04-15T10:35:35","guid":{"rendered":"https:\/\/cisnenegro.com.br\/?page_id=11862"},"modified":"2026-05-08T19:53:31","modified_gmt":"2026-05-08T22:53:31","slug":"home","status":"publish","type":"page","link":"https:\/\/cisnenegro.com.br\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<style>.kb-row-layout-id11862_87edba-27 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id11862_87edba-27 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id11862_87edba-27 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:100px;padding-bottom:100px;padding-left:100px;min-height:45vw;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11862_87edba-27{background-image:url('https:\/\/cisnenegro.com.br\/wp-content\/uploads\/746_2248.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id11862_87edba-27 > .kt-row-layout-overlay{opacity:0.66;background-color:#1b3039;mix-blend-mode:normal;}.kb-row-layout-id11862_87edba-27{z-index:682;position:relative;}@media all and (max-width: 1024px){.kb-row-layout-id11862_87edba-27 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11862_87edba-27 > .kt-row-column-wrap{min-height:80vw;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id11862_87edba-27 alignfull has-theme-palette5-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column11862_c7b3f7-28 > .kt-inside-inner-col,.kadence-column11862_c7b3f7-28 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11862_c7b3f7-28 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column11862_c7b3f7-28 > .kt-inside-inner-col{flex-direction:column;}.kadence-column11862_c7b3f7-28 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column11862_c7b3f7-28 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11862_c7b3f7-28{position:relative;}@media all and (max-width: 1024px){.kadence-column11862_c7b3f7-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column11862_c7b3f7-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11862_c7b3f7-28 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading11862_793231-51, .wp-block-kadence-advancedheading.kt-adv-heading11862_793231-51[data-kb-block=\"kb-adv-heading11862_793231-51\"]{text-align:left;font-size:5em;line-height:1.7em;font-weight:100;font-style:normal;font-family:Lato;color:#fff;}.wp-block-kadence-advancedheading.kt-adv-heading11862_793231-51 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading11862_793231-51[data-kb-block=\"kb-adv-heading11862_793231-51\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading11862_793231-51 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading11862_793231-51[data-kb-block=\"kb-adv-heading11862_793231-51\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading11862_793231-51, .wp-block-kadence-advancedheading.kt-adv-heading11862_793231-51[data-kb-block=\"kb-adv-heading11862_793231-51\"]{font-size:2.3em;text-align:left!important;}}<\/style>\n<h1 class=\"kt-adv-heading11862_793231-51 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading11862_793231-51\">Cisne Negro Cia de Dan\u00e7a<\/h1>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns11862_680810-c9{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns11862_680810-c9 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns11862_680810-c9\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn11862_03fee6-e8.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn11862_03fee6-e8.kb-button{color:#ffffff;border-top-color:#ffffff;border-top-style:solid;border-right-color:#ffffff;border-right-style:solid;border-bottom-color:#ffffff;border-bottom-style:solid;border-left-color:#ffffff;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn11862_03fee6-e8.kb-button{border-top-color:#ffffff;border-top-style:solid;border-right-color:#ffffff;border-right-style:solid;border-bottom-color:#ffffff;border-bottom-style:solid;border-left-color:#ffffff;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn11862_03fee6-e8.kb-button{border-top-color:#ffffff;border-top-style:solid;border-right-color:#ffffff;border-right-style:solid;border-bottom-color:#ffffff;border-bottom-style:solid;border-left-color:#ffffff;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn11862_03fee6-e8 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/cisnenegro.com.br\/a-companhia\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">A Companhia<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id11862_4dcba2-f2{margin-top:0px;margin-bottom:var(--global-kb-spacing-4xl, 8rem);}.kb-row-layout-id11862_4dcba2-f2 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id11862_4dcba2-f2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id11862_4dcba2-f2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:1207px;margin-left:auto;margin-right:auto;padding-bottom:var(--global-kb-spacing-lg, 3rem);min-height:340px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id11862_4dcba2-f2{background-image:url('https:\/\/cisnenegro.com.br\/wp-content\/uploads\/header-post-qn36anos-1.jpg');background-size:cover;background-position:30% 76%;background-attachment:fixed;background-repeat:no-repeat;}.kb-row-layout-id11862_4dcba2-f2 > .kt-row-layout-overlay{opacity:0.50;background-color:var(--global-palette3, #1A202C);mix-blend-mode:normal;}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id11862_4dcba2-f2{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-id11862_4dcba2-f2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id11862_4dcba2-f2 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-none, 0rem );max-width:610px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id11862_4dcba2-f2 alignfull kt-row-has-bg kt-jarallax wp-block-kadence-rowlayout\" data-img-position=\"30% 76%\" data-img-size=\"cover\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{display:flex;}.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{padding-top:0px;}.kadence-column11862_f43bc3-41 > .kt-inside-inner-col,.kadence-column11862_f43bc3-41 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{row-gap:0px;column-gap:7px;}.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column11862_f43bc3-41 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column11862_f43bc3-41{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11862_f43bc3-41{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column11862_f43bc3-41 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column11862_f43bc3-41{text-align:center;}.kadence-column11862_f43bc3-41{position:relative;}.kadence-column11862_f43bc3-41, .kt-inside-inner-col > .kadence-column11862_f43bc3-41:not(.specificity){margin-top:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column11862_f43bc3-41{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11862_f43bc3-41{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column11862_f43bc3-41{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11862_f43bc3-41{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column11862_f43bc3-41 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column11862_f43bc3-41 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-aa2d63a9860d2dfd8f2faacf7a033ecd\">A CISNE NEGRO CIA. DE DAN\u00c7A, dirigida artisticamente por Dany Bittencourt, \u00e9 uma das principais companhias contempor\u00e2neas do Brasil, celebrada tanto pela cr\u00edtica quanto pelo p\u00fablico. Com 49 anos de hist\u00f3ria e uma vis\u00e3o voltada para o futuro, acredita no poder da cultura como agente de transforma\u00e7\u00e3o social, nutrindo esperan\u00e7a e sonhos.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns11862_be76b3-0f{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns11862_be76b3-0f .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns11862_be76b3-0f{align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns11862_be76b3-0f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button{color:#fff;background:transparent;font-size:18px;border-top-left-radius:3px;border-top-right-radius:3px;border-bottom-right-radius:3px;border-bottom-left-radius:3px;border-top:2px solid #fff;border-right:2px solid #fff;border-bottom:2px solid #fff;border-left:2px solid #fff;padding-top:0px;margin-top:0px;}.wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button:focus{color:#fff;background:#008c9e;border-top-color:#008c9e;border-top-style:solid;border-right-color:#008c9e;border-right-style:solid;border-bottom-color:#008c9e;border-bottom-style:solid;border-left-color:#008c9e;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button{border-top:2px solid #fff;border-right:2px solid #fff;border-bottom:2px solid #fff;border-left:2px solid #fff;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button:focus{border-top-color:#008c9e;border-top-style:solid;border-right-color:#008c9e;border-right-style:solid;border-bottom-color:#008c9e;border-bottom-style:solid;border-left-color:#008c9e;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button{border-top:2px solid #fff;border-right:2px solid #fff;border-bottom:2px solid #fff;border-left:2px solid #fff;padding-bottom:0px;margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn11862_cf7686-be.kb-button:focus{border-top-color:#008c9e;border-top-style:solid;border-right-color:#008c9e;border-right-style:solid;border-bottom-color:#008c9e;border-bottom-style:solid;border-left-color:#008c9e;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn11862_cf7686-be kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/cisnenegro.com.br\/repertorio\/\"><span class=\"kt-btn-inner-text\">Nossa Hist\u00f3ria em Coreografias<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/section>\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-style:normal;font-weight:100\"><strong>A Cisne Negro Cia. de Dan\u00e7a tem o apoio de:<\/strong><\/h2>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-11862_65954e-df{margin-top:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-11862_65954e-df{margin:-15px;}.kb-gallery-type-grid.kb-gallery-id-11862_65954e-df .kadence-blocks-gallery-item{padding:15px;}.kb-gallery-id-11862_65954e-df .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-11862_65954e-df .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-caption-style-bottom.kb-gallery-id-11862_65954e-df .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption, .kb-gallery-caption-style-bottom-hover.kb-gallery-id-11862_65954e-df .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{background:linear-gradient(0deg, rgba(0, 0, 0, 0.8) 0, rgba(0, 0, 0, 0) 100%);}@media all and (max-width: 1024px){.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-11862_65954e-df{margin-top:0em;margin-right:1em;margin-bottom:0em;margin-left:1em;}}@media all and (max-width: 767px){.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-11862_65954e-df{margin-top:0em;margin-right:0em;margin-bottom:0em;margin-left:0em;}}<\/style><div class=\"kb-gallery-wrap-id-11862_65954e-df alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-11862_65954e-df kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"6\" data-columns-xl=\"6\" data-columns-md=\"6\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"3\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/camarim-logo-2024-300x212.jpg\" width=\"300\" height=\"212\" alt=\"Camarim Apoio Cisne Negro\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/camarim-logo-2024.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/camarim-logo-2024.jpg\" data-id=\"16178\" class=\"wp-image-16178\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/camarim-logo-2024-300x212.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/camarim-logo-2024-18x12.jpg 18w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/camarim-logo-2024.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">CAMARIM<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Capezio-Site-Cisne-Negro-Cia-de-Danca-2025-copy-300x200.jpg\" width=\"300\" height=\"200\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Capezio-Site-Cisne-Negro-Cia-de-Danca-2025-copy.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Capezio-Site-Cisne-Negro-Cia-de-Danca-2025-copy.jpg\" data-id=\"19216\" class=\"wp-image-19216\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Capezio-Site-Cisne-Negro-Cia-de-Danca-2025-copy-300x200.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Capezio-Site-Cisne-Negro-Cia-de-Danca-2025-copy.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.colegiolema.com.br\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Lema-Site-Cisne-Negro-Cia-de-Danca-2025-300x200.jpg\" width=\"300\" height=\"200\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Lema-Site-Cisne-Negro-Cia-de-Danca-2025.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Lema-Site-Cisne-Negro-Cia-de-Danca-2025.jpg\" data-id=\"17278\" class=\"wp-image-17278\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Lema-Site-Cisne-Negro-Cia-de-Danca-2025-300x200.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Lema-Site-Cisne-Negro-Cia-de-Danca-2025-18x12.jpg 18w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Lema-Site-Cisne-Negro-Cia-de-Danca-2025.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">COL\u00c9GIO LEMA<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/objetivo.br\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Objetivo-Cisne-Negro-Cia-de-Danca.jpg\" width=\"300\" height=\"212\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Objetivo-Cisne-Negro-Cia-de-Danca.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Objetivo-Cisne-Negro-Cia-de-Danca.jpg\" data-id=\"17258\" class=\"wp-image-17258\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Objetivo-Cisne-Negro-Cia-de-Danca.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Colegio-Objetivo-Cisne-Negro-Cia-de-Danca-18x12.jpg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">OBJETIVO<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.colorado.com.br\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/grupo-colorado2-logo-2024-300x212.png\" width=\"300\" height=\"212\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/grupo-colorado2-logo-2024.png\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/grupo-colorado2-logo-2024.png\" data-id=\"16225\" class=\"wp-image-16225\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/grupo-colorado2-logo-2024-300x212.png 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/grupo-colorado2-logo-2024-18x12.png 18w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/grupo-colorado2-logo-2024.png 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">COLORADO<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.iorm.org.br\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LOGO-IORM-Logo-2024-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LOGO-IORM-Logo-2024.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LOGO-IORM-Logo-2024.jpg\" data-id=\"16182\" class=\"wp-image-16182\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LOGO-IORM-Logo-2024-300x212.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LOGO-IORM-Logo-2024-18x12.jpg 18w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LOGO-IORM-Logo-2024.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">IORM<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.itau.com.br\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Itau-Site-Cisne-Negro-Cia-de-Danca-2025-2-300x300.jpg\" width=\"300\" height=\"300\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Itau-Site-Cisne-Negro-Cia-de-Danca-2025-2.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Itau-Site-Cisne-Negro-Cia-de-Danca-2025-2.jpg\" data-id=\"17268\" class=\"wp-image-17268\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Itau-Site-Cisne-Negro-Cia-de-Danca-2025-2-300x300.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Itau-Site-Cisne-Negro-Cia-de-Danca-2025-2-150x150.jpg 150w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Itau-Site-Cisne-Negro-Cia-de-Danca-2025-2-12x12.jpg 12w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Itau-Site-Cisne-Negro-Cia-de-Danca-2025-2.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">ITA\u00da<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/jacquesjanine.com.br\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/jacques-janine-logo-2024-300x212.jpg\" width=\"300\" height=\"212\" alt=\"Jacques Janine Apoio Cisne Negro\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/jacques-janine-logo-2024.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/jacques-janine-logo-2024.jpg\" data-id=\"16226\" class=\"wp-image-16226\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/jacques-janine-logo-2024-300x212.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/jacques-janine-logo-2024-18x12.jpg 18w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/jacques-janine-logo-2024.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">JACQUES JANINE<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.instagram.com\/clinica_lauraproenca\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LAURA-PROENCA-logo-2024-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LAURA-PROENCA-logo-2024.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LAURA-PROENCA-logo-2024.jpg\" data-id=\"16181\" class=\"wp-image-16181\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LAURA-PROENCA-logo-2024-300x212.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LAURA-PROENCA-logo-2024-18x12.jpg 18w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/LAURA-PROENCA-logo-2024.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">LAURA PROEN\u00c7A FISIOTERAPI<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.instagram.com\/luarconteudo\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Luar-Logo-2024-300x212.jpg\" width=\"300\" height=\"212\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Luar-Logo-2024.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Luar-Logo-2024.jpg\" data-id=\"16231\" class=\"wp-image-16231\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Luar-Logo-2024-300x212.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Luar-Logo-2024-18x12.jpg 18w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Luar-Logo-2024.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">LUAR<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/preteus.com\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/logo-preteus.png\" width=\"300\" height=\"212\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/logo-preteus.png\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/logo-preteus.png\" data-id=\"16604\" class=\"wp-image-16604\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/logo-preteus.png 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/logo-preteus-18x12.png 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">PRETEUS<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/www.unip.br\/\" class=\"kb-gallery-item-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Unip-Site-Cisne-Negro-Cia-de-Danca-2025-2-300x200.jpg\" width=\"300\" height=\"200\" alt=\"\" data-full-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Unip-Site-Cisne-Negro-Cia-de-Danca-2025-2.jpg\" data-light-image=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Unip-Site-Cisne-Negro-Cia-de-Danca-2025-2.jpg\" data-id=\"17271\" class=\"wp-image-17271\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Unip-Site-Cisne-Negro-Cia-de-Danca-2025-2-300x200.jpg 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Unip-Site-Cisne-Negro-Cia-de-Danca-2025-2-18x12.jpg 18w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Logo-Unip-Site-Cisne-Negro-Cia-de-Danca-2025-2.jpg 350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">UNIP<\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><strong>Realiza\u00e7\u00e3o<\/strong><\/h2>\n\n\n<style>.kb-image11862_521a77-0d .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image11862_521a77-0d is-style-default\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"147\" src=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Ministerio-da-Cultura-Barra-de-Logo-Cisne-Negro-48-Anos.png\" alt=\"Ministerio da Cultura Barra de Logo Cisne Negro 48 Anos\" class=\"kb-img wp-image-17228\" title=\"\" srcset=\"https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Ministerio-da-Cultura-Barra-de-Logo-Cisne-Negro-48-Anos.png 1024w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Ministerio-da-Cultura-Barra-de-Logo-Cisne-Negro-48-Anos-300x43.png 300w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Ministerio-da-Cultura-Barra-de-Logo-Cisne-Negro-48-Anos-768x110.png 768w, https:\/\/cisnenegro.com.br\/wp-content\/uploads\/Ministerio-da-Cultura-Barra-de-Logo-Cisne-Negro-48-Anos-18x3.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cisne Negro Cia de Dan\u00e7a A CISNE NEGRO CIA. DE DAN\u00c7A, dirigida artisticamente por Dany Bittencourt, \u00e9 uma das principais companhias contempor\u00e2neas do Brasil, celebrada tanto pela cr\u00edtica quanto pelo p\u00fablico. Com 49 anos de hist\u00f3ria e uma vis\u00e3o voltada para o futuro, acredita no poder da cultura como agente de transforma\u00e7\u00e3o social, nutrindo esperan\u00e7a&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"disable","_kad_post_title":"hide","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-11862","page","type-page","status-publish","hentry"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Cisne Negro Cia de Dan\u00e7a","author_link":"https:\/\/cisnenegro.com.br\/en\/author\/olhara\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/cisnenegro.com.br\/en\/wp-json\/wp\/v2\/pages\/11862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cisnenegro.com.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cisnenegro.com.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cisnenegro.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cisnenegro.com.br\/en\/wp-json\/wp\/v2\/comments?post=11862"}],"version-history":[{"count":317,"href":"https:\/\/cisnenegro.com.br\/en\/wp-json\/wp\/v2\/pages\/11862\/revisions"}],"predecessor-version":[{"id":19220,"href":"https:\/\/cisnenegro.com.br\/en\/wp-json\/wp\/v2\/pages\/11862\/revisions\/19220"}],"wp:attachment":[{"href":"https:\/\/cisnenegro.com.br\/en\/wp-json\/wp\/v2\/media?parent=11862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}